{"id":273,"date":"2022-10-31T08:00:00","date_gmt":"2022-10-31T07:00:00","guid":{"rendered":"https:\/\/www.akomet.com\/blog-tech\/?p=273"},"modified":"2023-06-07T12:07:13","modified_gmt":"2023-06-07T10:07:13","slug":"ottimizzare-blog-aziendale","status":"publish","type":"post","link":"https:\/\/www.akomet.com\/blog-tech\/ottimizzare-blog-aziendale-273\/","title":{"rendered":"Come ottimizzare i contenuti del tuo blog aziendale per i motori di ricerca"},"content":{"rendered":"\n<p>Quando si crea un <strong>blog per il tuo sito aziendale<\/strong> bisogna identificare prima di tutto il pubblico di destinazione indipendentemente dal settore a cui si rivolge il tuo blog e il tuo sito aziendale.<\/p>\n\n\n\n<p><strong>Capire chi \u00e8 il tuo pubblico di riferimento<\/strong> ti aiuter\u00e0 a guidare la strategia del tuo blog aziendale. Senza questa differenziazione potresti produrre contenuti accurati ma non adatti al tuo pubblico di riferimento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Scopriamo come ottimizzare i contenuti del vostro blog aziendale.<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Condurre una ricerca per parole chiave.<\/strong><\/h3>\n\n\n\n<p>Ora che hai selezionato il tuo pubblico di destinazione ed intercettato un possibile acquirente, \u00e8 tempo di scoprire a quali <strong>contenuti sono interessati i tuoi lettori<\/strong>. La ricerca delle parole chiave pu\u00f2 essere un compito difficile da affrontare se non si inizia con una strategia. Pertanto ti consigliamo di iniziare con gli argomenti che tratter\u00e0 il tuo blog, quindi espandere o ridurre il tuo ambito da l\u00ec, oppure affidarti a <strong><a href=\"\/servizi\/creazione-blog-professionali\/\" data-type=\"URL\" data-id=\"\/servizi\/creazione-blog-professionali\/\">professionisti come Akomet per creare la giusta strategia<\/a><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Aggiungi elementi visivi.<\/strong><\/h3>\n\n\n\n<p>I <strong>motori di ricerca come Google<\/strong> apprezzano gli elementi visivi per determinate parole chiave. Immagini e video sono tra gli elementi visivi pi\u00f9 comuni che appaiono nella pagina dei risultati dei motori di ricerca. Per ottenere un posto ambito in un <strong>pacchetto di immagini o in uno snippet di video<\/strong> ti consigliamo di <strong>progettare una grafica creativa<\/strong>, utilizzare <strong>foto e video originali <\/strong>e aggiungere un testo alternativo e descrittivo a ogni elemento visivo all&#8217;interno degli articoli del tuo blog aziendale.<\/p>\n\n\n\n<p>Il <strong>testo alternativo<\/strong> \u00e8 un fattore importante che determina se la tua <strong>immagine o video appare o meno nella SERP<\/strong> e quanto pu\u00f2 apparire. Il testo alternativo \u00e8 importante anche per i lettori di schermo in modo che le persone ipovedenti abbiano un&#8217;esperienza positiva nell&#8217;utilizzo dei contenuti del tuo blog aziendale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Scrivi un titolo accattivante.<\/strong><\/h3>\n\n\n\n<p>Il <strong>titolo del tuo articolo sul blog<\/strong> \u00e8 il primo elemento che un lettore vedr\u00e0 quando si imbatter\u00e0 nel tuo articolo e influenzer\u00e0 azione del cliccare per leggere il contenuto o passare oltre. Un titolo accattivante porter\u00e0 a suscitare l&#8217;interesse del lettore.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Includi una CTA allettante.<\/strong><\/h3>\n\n\n\n<p><strong>Che cos&#8217;\u00e8 un articolo sul blog senza un invito all&#8217;azione?<\/strong> Lo scopo di una CTA efficace \u00e8 incentivare il tuo lettore ad andare avanti a scoprire il tuo blog aziendale. Che tu stia vendendo un prodotto, offrendo un abbonamento a una newsletter o che desideri il lettore consumi pi\u00f9 contenuti, avrai bisogno di un invito all&#8217;azione allettante su ogni articolo del blog che pubblichi.<\/p>\n\n\n\n<p>I CTA sono disponibili in tutti i tipi di formati, quindi sii creativo e sperimentali. <strong>Pulsanti, collegamenti ipertestuali e widget<\/strong> sono alcuni dei CTA pi\u00f9 comuni e hanno tutti scopi diversi.<\/p>\n\n\n\n<p>Ad esempio, dovresti aggiungere una <strong>CTA in grassetto e visibile come un pulsante<\/strong> se desideri che il lettore effettui un acquisto. D&#8217;altra parte puoi facilmente convincere un lettore a controllare un altro articolo del blog fornendo un collegamento ipertestuale ad esso nella conclusione dell&#8217;articolo corrente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Concentrati sull&#8217;esperienza del lettore.<\/strong><\/h3>\n\n\n\n<p>Qualsiasi grande scrittore o SEO ti dir\u00e0 che l&#8217;esperienza del lettore \u00e8 la parte pi\u00f9 importante di un articolo sul tuo blog. <strong>L&#8217;esperienza del lettore<\/strong> include diversi fattori come <strong>leggibilit\u00e0, formattazione e velocit\u00e0 della pagina<\/strong>. Ci\u00f2 significa che dovrai scrivere contenuti chiari, completi ed accurati sul tuo argomento in base ai dati e alle tendenze pi\u00f9 recenti.<\/p>\n\n\n\n<p>Anche l&#8217;organizzazione del contenuto, utilizzando <strong>intestazioni e sottotitoli<\/strong>, \u00e8 importante perch\u00e9 aiuta il lettore a scansionare rapidamente il contenuto per trovare le informazioni di cui ha bisogno. Infine gli elementi sulla pagina come immagini e video hanno un impatto sulla velocit\u00e0 della pagina.<\/p>\n\n\n\n<p>Mantieni basse le dimensioni del file immagine (<strong>250 KB \u00e8 un buon punto di partenza<\/strong>) e limita il numero di video che incorpori in una singola pagina. Concentrati su ci\u00f2 che il lettore vuole sapere e organizza gli articoli in modo da raggiungere tale obiettivo; altrimenti affidati a <strong><a href=\"\/servizi\/creazione-contenuti-editoriali\/\" data-type=\"URL\" data-id=\"\/servizi\/creazione-contenuti-editoriali\/\">professionisti come il Team di Akomet per creare un blog aziendale di successo con articoli interessanti per i tuoi clienti<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vediamo come ottimizzare i contenuti del tuo blog aziendale per i motori di ricerca, indipendentemente dal settore a cui si rivolge la tua attivit\u00e0.<\/p>\n","protected":false},"author":1,"featured_media":274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-273","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-siti-web"},"spectra_custom_meta":{"_edit_lock":["1686132434:1"],"_edit_last":["1"],"_yoast_wpseo_title":["Ottimizzare il tuo blog per i motori di ricerca"],"_yoast_wpseo_metadesc":["Vediamo come ottimizzare i contenuti del tuo blog aziendale per i motori di ricerca, indipendentemente dal settore a cui si rivolge la tua attivit\u00e0."],"article-86-schema-type-fieldtype":["global-field"],"article-86-schema-type":["Article"],"article-86-author-fieldtype":["global-field"],"article-86-author":["author_name"],"article-86-author-url-fieldtype":["global-field"],"article-86-author-url":["author_url"],"article-86-image-fieldtype":["global-field"],"article-86-image":["featured_img"],"article-86-description-fieldtype":["global-field"],"article-86-description":["post_excerpt"],"article-86-main-entity-fieldtype":["global-field"],"article-86-main-entity":["post_permalink"],"article-86-name-fieldtype":["global-field"],"article-86-name":["post_title"],"article-86-published-date-fieldtype":["global-field"],"article-86-published-date":["post_date"],"article-86-modified-date-fieldtype":["global-field"],"article-86-modified-date":["post_modified"],"article-86-orgnization-name-fieldtype":["custom-field"],"article-86-orgnization-name":["Akomet"],"article-86-site-logo-fieldtype":["global-field"],"article-86-site-logo":["site_logo"],"_thumbnail_id":["274"],"custom-markup-372-custom-markup-fieldtype":["custom-field"],"custom-markup-372-custom-markup":["<script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"CreativeWorkSeries\",\"name\":\"Ottimizzare il tuo blog per i motori di ricerca\",\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5\",\"bestRating\":\"5\",\"ratingCount\":\"57\"}}<\/script>"],"_uagb_toc_options":["a:2:{s:17:\"_uagb_toc_version\";s:10:\"1686127597\";s:18:\"_uagb_toc_headings\";a:6:{i:0;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:64:\"scopriamo-come-ottimizzare-i-contenuti-del-vostro-blog-aziendale\";s:7:\"content\";s:65:\"Scopriamo come ottimizzare i contenuti del vostro blog aziendale.\";s:5:\"depth\";i:2;}i:1;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:40:\"1-condurre-una-ricerca-per-parole-chiave\";s:7:\"content\";s:42:\"1. Condurre una ricerca per parole chiave.\";s:5:\"depth\";i:3;}i:2;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:26:\"2-aggiungi-elementi-visivi\";s:7:\"content\";s:28:\"2. Aggiungi elementi visivi.\";s:5:\"depth\";i:3;}i:3;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:31:\"3-scrivi-un-titolo-accattivante\";s:7:\"content\";s:33:\"3. Scrivi un titolo accattivante.\";s:5:\"depth\";i:3;}i:4;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:28:\"4-includi-una-cta-allettante\";s:7:\"content\";s:30:\"4. Includi una CTA allettante.\";s:5:\"depth\";i:3;}i:5;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:40:\"5-concentrati-sullesperienza-del-lettore\";s:7:\"content\";s:43:\"5. Concentrati sull'esperienza del lettore.\";s:5:\"depth\";i:3;}}}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:5642:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n.wp-block-uagb-table-of-contents .uagb-toc__wrap{display:inline-block;max-width:-moz-available;max-width:-webkit-fill-available;max-width:fill-available}.wp-block-uagb-table-of-contents li.uagb-toc__list{padding-top:10px}.wp-block-uagb-table-of-contents ul.uagb-toc__list,.wp-block-uagb-table-of-contents ol.uagb-toc__list{list-style-position:inside;padding-left:0;margin-bottom:0;margin-left:2.2em}.wp-block-uagb-table-of-contents ul.uagb-toc__list li,.wp-block-uagb-table-of-contents ol.uagb-toc__list li{margin:0}.wp-block-uagb-table-of-contents ul li:empty{display:none}.wp-block-uagb-table-of-contents .uagb-toc__title-wrap{display:flex;align-items:center}.wp-block-uagb-table-of-contents .uagb-toc__title{display:flex;align-items:center}.wp-block-uagb-table-of-contents .uagb-toc__is-collapsible.uagb-toc__title-wrap{cursor:pointer}.wp-block-uagb-table-of-contents .uag-toc__collapsible-wrap svg{width:20px;height:20px}.wp-block-uagb-table-of-contents svg{width:20px;height:20px;display:inline-block;margin-left:10px;cursor:pointer}.wp-block-uagb-table-of-contents .uag-toc__collapsible-wrap{display:flex;margin-left:10px;cursor:pointer}.wp-block-uagb-table-of-contents.uagb-toc__collapse .uagb-toc__list-wrap{display:none}.wp-block-uagb-table-of-contents.uagb-toc__collapse--list ul.uagb-toc__list,.wp-block-uagb-table-of-contents.uagb-toc__collapse--list ol.uagb-toc__list{padding-left:2px}ol.uagb-toc__list li.uagb-toc__list ul,ol.uagb-toc__list ul.uagb-toc__list ul{list-style-type:circle}ol.uagb-toc__list>ul,ol.uagb-toc__list>li{list-style-type:disc}.uagb-toc__scroll-top{position:fixed;right:50px;bottom:50px;display:none;padding:10px;background:#ccd0d4;cursor:pointer;font-size:1rem;line-height:1.85714285714286}.uagb-toc__scroll-top svg{width:1.6em;height:0.6em;margin-left:0;transform:translate(0, -20%) rotate(180deg);fill:currentColor}.uagb-toc__scroll-top.uagb-toc__show-scroll{display:inline-table}body[class*=\"astra\"] .uagb-toc__list{line-height:normal}.uagb-toc__list{margin-top:0}.wp-block-uagb-table-of-contents ol.uagb-toc__list li.uagb-toc__list.uagb-toc__list--expandable{list-style-type:none !important}ul.uagb-toc__list--child-of-closed-list{padding-top:0 !important}ul.uagb-toc__list--hidden-child{display:none !important}.list-open::before,.list-collapsed::before{content:\"\\25BC\" \/ \"\";transition:transform 0.3s ease;transform:scale(0.7) translateX(-50%);display:inline-block}.list-collapsed::before{transform:scale(0.7) rotate(-90deg) translate(-84%, 6%)}span.list-open,span.list-collapsed{cursor:pointer;outline:none !important}.uagb-toc__list.transition{transition:max-height 300ms ease-in-out, padding-top 300ms ease-in-out}.uagb-toc__loader{border:2px solid #f3f3f3;border-top:2px solid #0073aa;border-radius:50%;width:20px;height:20px;animation:spin 1.1s linear infinite;display:block;position:absolute;margin-top:5px}.uagb-toc__list-hidden{opacity:0}@keyframes spin{0%{transform:rotate(0deg)}100%{transform:rotate(360deg)}}[dir=\"rtl\"] .list-open::before{transform:scale(0.7) translateX(50%)}[dir=\"rtl\"] .list-collapsed::before{transform:scale(0.7) rotate(90deg) translate(84%, 6%)}[dir=\"rtl\"] .wp-block-uagb-table-of-contents.uagb-toc__collapse--list ul.uagb-toc__list,[dir=\"rtl\"] .wp-block-uagb-table-of-contents.uagb-toc__collapse--list ol.uagb-toc__list{padding-left:0;padding-right:2px;margin-left:0;margin-right:2.2em}\n.uagb-block-aaa2511a.wp-block-uagb-table-of-contents{text-align: left;}.uagb-block-aaa2511a .uagb-toc__list-wrap li a{color: #54595F;}.uagb-block-aaa2511a .uagb-toc__wrap .uagb-toc__title-wrap{justify-content: left;}.uagb-block-aaa2511a .uagb-toc__wrap .uagb-toc__title{justify-content: left;}.uagb-block-aaa2511a .uagb-toc__wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: #333;border-style: solid;padding-left: 30px;padding-right: 30px;padding-top: 30px;padding-bottom: 30px;background: #fff;width: 100%;}.uagb-block-aaa2511a .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-aaa2511a .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-aaa2511a .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-aaa2511a .uagb-toc__list .uagb-toc__list{list-style-type: disc !important;}.uagb-block-aaa2511a .uagb-toc__title{font-weight: Default;font-size: 20px;}.uagb-block-aaa2511a .uagb-toc__list-wrap ol li a{text-decoration: underline;}@media only screen and (max-width: 976px) {.uagb-block-aaa2511a .uagb-toc__wrap{border-style: solid;}.uagb-block-aaa2511a .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-aaa2511a .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-aaa2511a .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}}@media only screen and (max-width: 767px) {.uagb-block-aaa2511a .uagb-toc__wrap{border-style: solid;}.uagb-block-aaa2511a .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-aaa2511a .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-aaa2511a .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}}\";s:2:\"js\";s:383:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function(){\n\tUAGBTableOfContents._run( {\"mappingHeaders\":[true,true,true,true,true,true],\"scrollToTop\":false,\"makeCollapsible\":false,\"enableCollapsableList\":false,\"initialCollapse\":false,\"markerView\":\"disc\",\"isFrontend\":true,\"initiallyCollapseList\":false}, '.uagb-block-aaa2511a' );\n} );\n });\";s:18:\"current_block_list\";a:3:{i:0;s:14:\"core\/paragraph\";i:1;s:12:\"core\/heading\";i:2;s:22:\"uagb\/table-of-contents\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1750498599\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"wp_schema_pro_optimized_structured_data":["<!-- Schema optimized by Schema Pro --><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"Article\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.akomet.com\/blog-tech\/ottimizzare-blog-aziendale-273\/\"},\"headline\":\"Come ottimizzare i contenuti del tuo blog aziendale per i motori di ricerca\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg\",\"width\":1200,\"height\":675},\"datePublished\":\"2022-10-31T08:00:00+0000\",\"dateModified\":\"2023-06-07T12:07:13+0000\",\"author\":{\"@type\":\"Person\",\"name\":\"Team Akomet\",\"url\":\"https:\/\/www.akomet.com\/blog-tech\/author\/contatto\"},\"publisher\":{\"@type\":\"Organization\",\"name\":\"Akomet\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2021\/10\/cropped-icon-akomet-min.png\"}},\"description\":\"Vediamo come ottimizzare i contenuti del tuo blog aziendale per i motori di ricerca, indipendentemente dal settore a cui si rivolge la tua attivit\u00e0.\"}<\/script><!-- \/ Schema optimized by Schema Pro -->"],"rank_math_title":["Ottimizzare il tuo blog per i motori di ricerca"],"rank_math_description":["Vediamo come ottimizzare i contenuti del tuo blog aziendale per i motori di ricerca, indipendentemente dal settore a cui si rivolge la tua attivit\u00e0."],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"rank_math_schema_Article":["a:4:{s:8:\"headline\";s:11:\"%seo_title%\";s:11:\"description\";s:17:\"%seo_description%\";s:5:\"@type\";s:7:\"Article\";s:8:\"metadata\";a:4:{s:5:\"title\";s:7:\"Article\";s:4:\"type\";s:8:\"template\";s:9:\"isPrimary\";i:1;s:9:\"shortcode\";s:15:\"s-661af599f3631\";}}"],"rank_math_analytic_object_id":["71"],"rank_math_internal_links_processed":["1"],"_uag_css_file_name":["uag-css-273.css"],"_uag_js_file_name":["uag-js-273.js"]},"uagb_featured_image_src":{"full":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",1200,675,false],"thumbnail":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-200x113.jpg",200,113,true],"medium":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-400x225.jpg",400,225,true],"medium_large":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-768x432.jpg",768,432,true],"large":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-800x450.jpg",800,450,true],"1536x1536":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",1200,675,false],"2048x2048":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",1200,675,false],"newspack-article-block-landscape-large":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",1200,675,false],"newspack-article-block-portrait-large":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-900x675.jpg",900,675,true],"newspack-article-block-square-large":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",1200,675,false],"newspack-article-block-landscape-medium":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-800x600.jpg",800,600,true],"newspack-article-block-portrait-medium":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-600x675.jpg",600,675,true],"newspack-article-block-square-medium":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-800x675.jpg",800,675,true],"newspack-article-block-landscape-intermediate":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",600,338,false],"newspack-article-block-portrait-intermediate":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",450,253,false],"newspack-article-block-square-intermediate":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",600,338,false],"newspack-article-block-landscape-small":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-400x300.jpg",400,300,true],"newspack-article-block-portrait-small":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-300x400.jpg",300,400,true],"newspack-article-block-square-small":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-400x400.jpg",400,400,true],"newspack-article-block-landscape-tiny":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-200x150.jpg",200,150,true],"newspack-article-block-portrait-tiny":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-150x200.jpg",150,200,true],"newspack-article-block-square-tiny":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min-200x200.jpg",200,200,true],"newspack-article-block-uncropped":["https:\/\/www.akomet.com\/blog-tech\/wp-content\/uploads\/sites\/4\/2022\/10\/blog-6a-min.jpg",1200,675,false]},"uagb_author_info":{"display_name":"Team Akomet","author_link":"https:\/\/www.akomet.com\/blog-tech\/author\/contatto\/"},"uagb_comment_info":0,"uagb_excerpt":"Vediamo come ottimizzare i contenuti del tuo blog aziendale per i motori di ricerca, indipendentemente dal settore a cui si rivolge la tua attivit\u00e0.","_links":{"self":[{"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/posts\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/comments?post=273"}],"version-history":[{"count":0,"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/posts\/273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/media\/274"}],"wp:attachment":[{"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/media?parent=273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/categories?post=273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.akomet.com\/blog-tech\/wp-json\/wp\/v2\/tags?post=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}